{"id":313,"date":"2010-06-15T18:52:26","date_gmt":"2010-06-15T16:52:26","guid":{"rendered":"http:\/\/www.adeas.org\/?p=313"},"modified":"2010-06-15T18:52:26","modified_gmt":"2010-06-15T16:52:26","slug":"assemblee-generale-des-actionnaires-france-telecom-petites-manipulations-entre-amis","status":"publish","type":"post","link":"https:\/\/www.adeas.org\/index.php\/communique-de-presse\/assemblee-generale-des-actionnaires-france-telecom-petites-manipulations-entre-amis\/","title":{"rendered":"Assembl\u00e9e G\u00e9n\u00e9rale des Actionnaires France T\u00e9l\u00e9com : petites manipulations entre amis."},"content":{"rendered":"<p>Comme l\u2019a not\u00e9 <a href=\"http:\/\/www.challenges.fr\/actualites\/medias\/20100610.CHA4907\/richard_peine_a_justifier_son_interet_pour_le_monde.html\">Challenges<\/a>, les r\u00e9solutions propos\u00e9es par le Conseil d\u2019Administration de l\u2019entreprise au vote des actionnaires r\u00e9unis en Assembl\u00e9e G\u00e9n\u00e9rale, le 9 juin dernier, ont recueilli des scores de \u00ab\u00a0r\u00e9publique banani\u00e8re\u00a0\u00bb.<\/p>\n<p>Dans un monde de plus en plus complexe et financiaris\u00e9, peut-on encore pr\u00e9tendre que le vote des actionnaires est r\u00e9ellement \u00e9clair\u00e9\u00a0? La Direction de l\u2019entreprise en tous cas fait de son mieux pour le manipuler. Quelques exemples\u00a0?<\/p>\n<h3>Dividendes et pr\u00e9sentation des comptes\u00a0: \u00e0 quelle norme se vouer\u00a0?<\/h3>\n<p>La Direction a fond\u00e9 l\u2019essentiel de son discours financier sur la distribution d\u2019un dividende repr\u00e9sentant 45% du cash flow organique, arguant que ce ratio est plut\u00f4t dans le bas de la fourchette des pratiques pour les op\u00e9rateurs de t\u00e9l\u00e9communications.<\/p>\n<p>De fait, dans les <a href=\"http:\/\/www.orange.com\/fr_FR\/finance\/ag\/ag090610\/att00015689\/AG2010_ORANGE.pdf\">transparents de pr\u00e9sentation<\/a>, comme dans le discours qui l\u2019accompagnait, on ne trouve aucune r\u00e9f\u00e9rence au r\u00e9sultat net (b\u00e9n\u00e9fice) de l\u2019entreprise, tel que mentionn\u00e9 dans les comptes annuels ou dans les comptes consolid\u00e9s. Pourtant, l\u2019approbation des comptes \u00e9tait l\u2019objet des deux premi\u00e8res <a href=\"http:\/\/www.orange.com\/fr_FR\/finance\/ag\/ag090610\/att00014793\/WEB_AVC_FR_RESO.pdf\">r\u00e9solutions pr\u00e9sent\u00e9es au vote des actionnaires<\/a>. La premi\u00e8re mentionne une perte de 1,416 milliard d\u2019euros dans les comptes annuels. La seconde concerne les comptes consolid\u00e9s, transcrits dans le <a href=\"http:\/\/www.orange.com\/media\/doc-finance\/fr\/doc-reference\/att00015095\/DDR2009completCL28042010_17h06.pdf\">document de r\u00e9f\u00e9rence<\/a>. Le r\u00e9sultat net consolid\u00e9 distribuable aux propri\u00e9taires de la soci\u00e9t\u00e9 m\u00e8re y appara\u00eet pour un montant de 2,977 milliards d\u2019euros, soit 1,13 euro par action. Le total des dividendes distribu\u00e9s au titre de l\u2019exercice 2009, \u00e0 raison de 1,40 euro par action \u2013 objet de la troisi\u00e8me r\u00e9solution, se montera donc \u00e0 pr\u00e8s de 3,7 milliards d\u2019euros.<\/p>\n<p>Les actionnaires ont-ils pris le temps d\u2019\u00e9tudier les documents de r\u00e9f\u00e9rence de l\u2019entreprise\u00a0? Personne n\u2019a pos\u00e9 la question de ces \u00e9carts de chiffres, pourtant troublants, qui mettent en question la saine gestion de l\u2019entreprise (comment peut-on distribuer des dividendes sup\u00e9rieurs aux b\u00e9n\u00e9fices\u00a0?), mais aussi sa transparence financi\u00e8re, qui est une exigence pour une entreprise cot\u00e9e en bourse.<\/p>\n<p>Les trois premi\u00e8res r\u00e9solutions ont \u00e9t\u00e9 adopt\u00e9es avec les <a href=\"http:\/\/www.orange.com\/fr_FR\/finance\/ag\/ag090610\/vote_AG.jsp\">scores<\/a> respectifs de 98,47 %, 99,87 % et 98,24 %, soit le pourcentage de suffrages exprim\u00e9s par les actionnaires pr\u00e9sents ou repr\u00e9sent\u00e9s (quorum de 61,52% pour l\u2019AG 2010)<\/p>\n<p>Pour pond\u00e9rer ces r\u00e9sultats, rappelons que l\u2019\u00c9tat d\u00e9tient, directement ou via le FSI (Fonds Strat\u00e9gique d\u2019Investissement), 27% des parts (ce qui le positionne comme principal b\u00e9n\u00e9ficiaire des dividendes), et que le vote des salari\u00e9s actionnaires, qui repr\u00e9sentent environ 4% du capital, s\u2019exprime pour l\u2019essentiel au travers des fonds du plan d\u2019\u00e9pargne groupe, dont <a href=\"..\/..\/..\/..\/..\/index.php\/non-classe\/la-representation-des-salaries-actionnaires%E2%80%A6-ou-comment-une-os-devenue-non-representative-trahit-les-salaries-en-catimini\/comment-page-1\/#comment-341\">la Direction peut facilement orienter les votes avec l\u2019aide d\u2019une seule organisation syndicale<\/a> (dont le repr\u00e9sentant, sans surprise, a bien \u00e9t\u00e9 \u00e9lu par l\u2019AG en tant que repr\u00e9sentant des salari\u00e9s actionnaires, avec un score de 84,65% de vote positif \u00e0 la neuvi\u00e8me r\u00e9solution)\u00a0 Le reste des suffrages se r\u00e9partit entre les investisseurs institutionnels, y compris \u00e9trangers, et les petits porteurs pr\u00e9sents ou repr\u00e9sent\u00e9s.<\/p>\n<h3>6<sup>\u00e8me<\/sup> r\u00e9solution\u00a0: mensonge par omission<\/h3>\n<p>La pr\u00e9sentation de cette r\u00e9solution illustre particuli\u00e8rement bien comment il est facile de manipuler l\u2019opinion d\u2019une assembl\u00e9e. Il s\u2019agissait ici d\u2019approuver \u00ab\u00a0<em>les avenants aux contrats conclus entre la soci\u00e9t\u00e9 Novalis et la Soci\u00e9t\u00e9 relatifs aux frais de sant\u00e9 et \u00e0 la pr\u00e9voyance d\u00e9c\u00e8s-incapacit\u00e9-invalidit\u00e9 des mandataires sociaux de la Soci\u00e9t\u00e9<\/em> \u00bb.<\/p>\n<p>Cette r\u00e9solution a \u00e9t\u00e9 pr\u00e9sent\u00e9e avec l\u2019indication orale que tous les salari\u00e9s de l\u2019entreprise en b\u00e9n\u00e9ficient. Sous entendu\u00a0: il n\u2019y avait pas de raison d\u2019en priver les seuls mandataires sociaux.<\/p>\n<p>C\u2019est vrai, tous les salari\u00e9s b\u00e9n\u00e9ficient d\u2019une mutuelle obligatoire souscrite par le Groupe. Mais pas les fonctionnaires. Qui, comme cela a \u00e9t\u00e9 rappel\u00e9 lors de cette m\u00eame AG, repr\u00e9sentent 64% du personnel fran\u00e7ais, incluant d\u2019ailleurs le Pr\u00e9sident Lombard, fonctionnaire \u00e0 la retraite, qui s\u2019est donc assur\u00e9 une meilleure couverture sociale en faisant voter cette r\u00e9solution.<\/p>\n<h3>R\u00e9mun\u00e9rations\u00a0: comment noyer le poisson<\/h3>\n<p>Une actionnaire a pos\u00e9 la question des \u00e9carts de r\u00e9mun\u00e9ration, ainsi libell\u00e9e\u00a0: \u00ab\u00a0<em>quel est l\u2019\u00e9cart entre les dix plus fortes et les dix plus faibles r\u00e9mun\u00e9rations de l\u2019entreprise, et qu\u2019en pense le Conseil d\u2019Administration\u00a0?<\/em> \u00bb<\/p>\n<p>La seconde partie de la question n\u2019a pas obtenu de r\u00e9ponse. A la premi\u00e8re partie, il a \u00e9t\u00e9 r\u00e9pondu \u00ab\u00a0<em>l\u2019\u00e9cart entre la moyenne des 10% les mieux pay\u00e9s et la moyenne des 10% les plus mal pay\u00e9s est de 3,3<\/em> \u00bb. Cet \u00e9cart, mesur\u00e9 dans le bilan social de l\u2019entreprise, ne cesse d\u2019augmenter (+12% en 5 ans), alors m\u00eame que les plus bas salaires de l\u2019entreprise disparaissent, au profit de la sous-traitance, y compris d\u00e9localis\u00e9e.<\/p>\n<p>On peut cependant fournir d\u2019autres r\u00e9ponses. Page 316, le <a href=\"http:\/\/www.orange.com\/media\/doc-finance\/fr\/doc-reference\/att00015095\/DDR2009completCL28042010_17h06.pdf\">document de r\u00e9f\u00e9rence<\/a> de l\u2019entreprise mentionne les revenus du PDG de France T\u00e9l\u00e9com, Monsieur Didier Lombard, pour l\u2019exercice 2009\u00a0: 1 587\u00a0992 euros, dont 900\u00a0000 euros de r\u00e9mun\u00e9ration fixe. Les informations du <a href=\"http:\/\/www.orange.com\/fr_FR\/finance\/documentation\/rapports-annuels\/att00014092\/FTEL_RA2009_FR.pdf\">rapport annuel<\/a> permettent en parall\u00e8le d\u2019identifier 181\u00a0000 collaborateurs dans le monde (page 10), pour 9,094 milliards d\u2019euros de charges de personnel (page 86), soit en moyenne 50\u00a0000 euros par collaborateur. Exprim\u00e9 en revenu pour les personnes concern\u00e9es, c\u2019est donc un \u00e9cart d\u2019environ 1 \u00e0 50 entre les revenus du PDG et le revenu moyen par collaborateur de l\u2019entreprise.<\/p>\n<h3>\u00ab\u00a0Belles histoires\u00a0\u00bb\u00a0: les personnels de l\u2019entreprise esp\u00e8rent qu\u2019elles seront bient\u00f4t le cas g\u00e9n\u00e9ral<\/h3>\n<p>En visionnant les petits films projet\u00e9s devant l\u2019Assembl\u00e9e G\u00e9n\u00e9rale pour illustrer quelques parcours professionnels dans l\u2019entreprise, les personnels ont \u00e9t\u00e9 notamment surpris de constater qu\u2019on mettait en avant les plateaux d\u2019appels, dont on sait qu\u2019ils font partie des services de l\u2019entreprise les plus expos\u00e9s aux risques psycho-sociaux selon les r\u00e9sultats du rapport Technologia, ou encore un travailleur handicap\u00e9, lorsqu\u2019on sait que France T\u00e9l\u00e9com en la mati\u00e8re ne respecte ni le <a href=\"http:\/\/www.cfecgc-ft-orange.org\/ftsa\/index.php?option=com_content&amp;task=view&amp;id=1070&amp;Itemid=67\">pourcentage l\u00e9gal de travailleurs handicap\u00e9s dans l\u2019entreprise<\/a>, ni les accords qu\u2019elle a sign\u00e9s avec les organisations syndicales pour s\u2019en affranchir.<\/p>\n<p>Sans mettre en doute la sinc\u00e9rit\u00e9 des t\u00e9moignages pr\u00e9sent\u00e9s, on peut cependant noter le caract\u00e8re exceptionnel des parcours \u00e9voqu\u00e9s, et l\u2019habilet\u00e9 des communicants qui ont pr\u00e9par\u00e9 cette belle s\u00e9quence.<\/p>\n<p>Les personnels les plus sagaces n\u2019auront pas manqu\u00e9 de d\u00e9celer d\u2019autres \u00ab\u00a0d\u00e9tails\u00a0\u00bb du m\u00eame ordre, telle la composition du Comit\u00e9 Strat\u00e9gique, dont tout laisse \u00e0 penser qu\u2019il est constitu\u00e9 tout expr\u00e8s pour permettre au Pr\u00e9sident Lombard de valider toutes ses propositions, ou encore l\u2019incapacit\u00e9 de ce m\u00eame Pr\u00e9sident, qui rappelait pourtant assumer l\u2019enti\u00e8re responsabilit\u00e9 du pilotage de l\u2019entreprise pour l\u2019exercice 2009, \u00e0 revenir sur la crise sociale, encore moins \u00e0 pr\u00e9senter un quelconque mea-culpa. Il a pr\u00e9f\u00e9r\u00e9 engager l\u2019entreprise dans la promesse de poursuivre, pour l\u2019exercice 2010, la distribution d\u2019un dividende repr\u00e9sentant au moins 45% du cash flow organique, laissant \u00e0 St\u00e9phane Richard le soin de prendre le \u00ab\u00a0<em>tournant<\/em> \u00bb annonc\u00e9 dans les slides de pr\u00e9sentation, afin de surmonter la crise en travaillant sur un nouveau projet d\u2019entreprise.<\/p>\n<p><strong>L\u2019ADEAS ne peut qu\u2019inviter les actionnaires \u00e0 une vigilance toujours accrue dans l\u2019analyse des donn\u00e9es qui leur sont pr\u00e9sent\u00e9es, et la Direction de l\u2019entreprise \u00e0 une plus grande transparence, afin que la confiance puisse durablement se restaurer entre toutes les parties prenantes de l\u2019entreprise, personnels, actionnaires, clients, et soci\u00e9t\u00e9 civile, pour laquelle France T\u00e9l\u00e9com reste, de par son histoire, une entreprise embl\u00e9matique, et qui, \u00e0 ce titre, se doit d\u2019\u00eatre exemplaire.<\/strong><\/p>\n<ul>\n<li>T\u00e9l\u00e9charger le communiqu\u00e9 en pdf : <a href=\"https:\/\/www.adeas.org\/wp-content\/uploads\/2010\/06\/Communiqu\u00e9-ADEAS-AG-France-T\u00e9l\u00e9com-2010_15-juin-2010.pdf\">Communiqu\u00e9 ADEAS &#8211; AG France T\u00e9l\u00e9com 2010_15 juin 2010<\/a><strong><br \/>\n<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comme l\u2019a not\u00e9 Challenges, les r\u00e9solutions propos\u00e9es par le Conseil d\u2019Administration de l\u2019entreprise au vote des actionnaires r\u00e9unis en Assembl\u00e9e G\u00e9n\u00e9rale, le 9 juin dernier, ont recueilli des scores de \u00ab\u00a0r\u00e9publique banani\u00e8re\u00a0\u00bb. Dans un monde de plus en plus complexe et financiaris\u00e9, peut-on encore pr\u00e9tendre que le vote des actionnaires est r\u00e9ellement \u00e9clair\u00e9\u00a0? La Direction [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[22,11,42,36,34],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-communique-de-presse","tag-actionnariat","tag-actionnariat-salarie","tag-assemblee-generale","tag-dividendes","tag-remuneration"],"_links":{"self":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":3,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":317,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/313\/revisions\/317"}],"wp:attachment":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}