{"id":150,"date":"2010-01-08T09:54:24","date_gmt":"2010-01-08T08:54:24","guid":{"rendered":"http:\/\/www.adeas.org\/?p=150"},"modified":"2011-04-12T12:25:52","modified_gmt":"2011-04-12T10:25:52","slug":"le-site-web-amundi-remplace-celui-de-creelia","status":"publish","type":"post","link":"https:\/\/www.adeas.org\/index.php\/en-pratique\/le-site-web-amundi-remplace-celui-de-creelia\/","title":{"rendered":"Le site web Amundi remplace celui de Creelia"},"content":{"rendered":"<p><span style=\"color: #ff6600;\"><strong>Suite \u00e0 vos nombreux messages, nous nous devons de rappeler que  l&rsquo;ADEAS est une association de salari\u00e9s, enti\u00e8rement ind\u00e9pendante de la  banque gestionnaire des comptes d&rsquo;\u00e9pargne salariale du Groupe France  T\u00e9l\u00e9com, et en particulier que nous n&rsquo;avons pas la main sur le service  Amundi, qui est g\u00e9r\u00e9 par la banque.<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #ff6600;\"> En particulier, il  nous est techniquement impossible de d\u00e9bloquer les acc\u00e8s sur ce service  ou de renvoyer des codes d&rsquo;acc\u00e8s. Pour ce faire, vous devez contacter  directement la banque gestionnaire. Les coordonn\u00e9es des services clients  sont rappel\u00e9s dans la page : <a href=\"https:\/\/www.adeas.org\/index.php\/vos-codes-de-gestion\/ \">Vos codes de gestion<\/a>.<\/span><br \/>\n<\/strong><\/p>\n<p>D\u00e9sormais, pour vous connecter sur l\u2019outil de gestion de votre \u00e9pargne salariale (PEG et PERCO), vous devez vous connecter sur <a href=\"http:\/\/www.amundi-ee.com\/\">Amundi<\/a>. Vos identifiants et mots de passe restent les m\u00eames que pour l\u2019ancien site. L\u2019identifiant est votre num\u00e9ro de compte, qui figure sur tous les relev\u00e9s qui vous ont \u00e9t\u00e9 adress\u00e9s par Creelia.<\/p>\n<p>Sur le site web d&rsquo;Amundi, vous pourrez retrouver notamment\u00a0:<\/p>\n<h4>Menu de gauche \/ Votre compte\u00a0:<\/h4>\n<p>Vous y retrouvez les pages que vous aviez sur Creelia\u00a0:<\/p>\n<ul>\n<li>Votre \u00e9pargne salariale\u00a0= votre relev\u00e9 de compte, avec la r\u00e9partition de vos avoirs dans les diff\u00e9rents fonds et la valeur mon\u00e9taire correspondante, aux dates mentionn\u00e9es dans le relev\u00e9. Ces valeurs sont donc susceptibles de changer au fil du temps, et notamment ne seront pas forc\u00e9ment celles qui s\u2019appliqueront si vous demandez un d\u00e9blocage de vos avoirs.<\/li>\n<\/ul>\n<ul>\n<li>Vos op\u00e9rations = le relev\u00e9 de vos op\u00e9rations, et un sous-menu vous permettant de traiter des op\u00e9rations\u00a0: versement, arbitrage, transfert,\u00a0 remboursement<\/li>\n<\/ul>\n<ul>\n<li>Vos donn\u00e9es personnelles. N\u2019oubliez pas de les mettre \u00e0 jour r\u00e9guli\u00e8rement, notamment le mail et le mobile, tr\u00e8s utiles pour pouvoir redemander son mot de passe, et bien sur les coordonn\u00e9es bancaires, tout particuli\u00e8rement si vous pr\u00e9voyez des op\u00e9rations de versements ou de remboursements.<\/li>\n<\/ul>\n<ul>\n<li>Vos eServices = la consultation et le t\u00e9l\u00e9chargement en format pdf des relev\u00e9s de compte.<\/li>\n<\/ul>\n<ul>\n<li>Cas de d\u00e9blocage\u00a0= toute la documentation l\u00e9gale et les modalit\u00e9s d\u2019un d\u00e9blocage anticip\u00e9 de votre \u00e9pargne salariale, PEG (PEE sur le site) ou PERCO.<\/li>\n<\/ul>\n<h4>Menu de gauche \/ Vos services<\/h4>\n<ul>\n<li>Vous pouvez y consulter le dernier reporting, et en principe cr\u00e9er des alertes pour recevoir un mail lors de la publication d\u2019un nouveau reporting et\/ou si la valeur liquidative d\u00e9passe les valeurs que vous aurez indiqu\u00e9es dans la cr\u00e9ation de l\u2019alerte.<\/li>\n<\/ul>\n<h4>Menu de droite \u00ab\u00a0acc\u00e8s direct\u00a0\u00bb<\/h4>\n<ul>\n<li> Le lexique est tr\u00e8s utile pour comprendre les termes et abr\u00e9viations<\/li>\n<\/ul>\n<ul>\n<li>Les calculettes vous permettent notamment de d\u00e9terminer votre profil d\u2019investisseur, sur la base d\u2019un petit questionnaire.<\/li>\n<\/ul>\n<p>Nous poursuivrons l\u2019exploration du site au fil du temps. N\u2019h\u00e9sitez pas \u00e0 nous faire conna\u00eetre les fonctionnalit\u00e9s int\u00e9ressantes que vous aurez d\u00e9couvertes en l\u2019utilisant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 vos nombreux messages, nous nous devons de rappeler que l&rsquo;ADEAS est une association de salari\u00e9s, enti\u00e8rement ind\u00e9pendante de la banque gestionnaire des comptes d&rsquo;\u00e9pargne salariale du Groupe France T\u00e9l\u00e9com, et en particulier que nous n&rsquo;avons pas la main sur le service Amundi, qui est g\u00e9r\u00e9 par la banque. En particulier, il nous est [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[11,33,17],"class_list":["post-150","post","type-post","status-publish","format-standard","hentry","category-en-pratique","tag-actionnariat-salarie","tag-outils-web","tag-pratique"],"_links":{"self":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":7,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/posts\/150\/revisions\/152"}],"wp:attachment":[{"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adeas.org\/index.php\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}